{"id":8950,"date":"2026-07-14T18:04:10","date_gmt":"2026-07-14T21:04:10","guid":{"rendered":"https:\/\/museudoipiranga.org.br\/?p=8950"},"modified":"2026-07-14T18:04:10","modified_gmt":"2026-07-14T21:04:10","slug":"um-sonho","status":"publish","type":"post","link":"https:\/\/museudoipiranga.org.br\/en\/um-sonho\/","title":{"rendered":"A dream"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Ca\u00ed no Museu do Ipiranga de paraquedas.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Quando prestei o concurso, em 2024, achei que era para trabalhar no Museu de Arqueologia e Etnologia da Universidade de S\u00e3o Paulo. J\u00e1 havia realizado uma disciplina no Museu, durante o mestrado, e visitado a exposi\u00e7\u00e3o <\/span><i><span style=\"font-weight: 400;\">Resist\u00eancia J\u00e1! Fortalecimento e uni\u00e3o das culturas ind\u00edgenas Kaingang, Guarani Nhandewa e Terena<\/span><\/i><span style=\"font-weight: 400;\">, que se revelou especialmente significativa por ser resultado de um processo de curadoria compartilhada entre esses grupos ind\u00edgenas e os pesquisadores do Museu. Como a bibliografia da prova trazia temas relacionados a essa institui\u00e7\u00e3o, logo deduzi que a vaga seria para l\u00e1, embora houvesse a possibilidade de ser chamada para qualquer um dos museus administrados pela USP.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Fiquei em segundo lugar no concurso e, muito chateada, parei de verificar as atualiza\u00e7\u00f5es do site. A\u00ed um dia, abro meu e-mail, e me deparo com a seguinte mensagem:<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Parab\u00e9ns pela sua aprova\u00e7\u00e3o!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Lembro que estava em Ribeir\u00e3o Preto, na casa da minha m\u00e3e, e levei o computador at\u00e9 ela para perguntar se o que estava vendo era real. N\u00f3s duas come\u00e7amos a chorar. Telefonei para o meu pai, e ele desatou tamb\u00e9m. Depois, quando contei ao meu marido, ainda chorava tanto que ele achou que o meu cachorro tinha morrido.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Fazia uns tr\u00eas meses que tinha sa\u00eddo o resultado e, a princ\u00edpio, achei que apenas uma pessoa seria contemplada. A funcion\u00e1ria de Recursos Humanos me explicou que eu deveria me apresentar no Museu do Ipiranga e somente nesse momento entendi para onde havia sido selecionada. At\u00e9 perguntei:<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u2013 N\u00e3o \u00e9 no Museu de Arqueologia?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">N\u00e3o, n\u00e3o era. Naquela altura, j\u00e1 estava definido que eu iria para o Ipiranga e, embora tenha sido inesperado, fiquei muito empolgada com a oportunidade de atuar na \u00e1rea educativa de um museu.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Quando me mudei para S\u00e3o Paulo, em 2012, ainda como uma estudante de Comunica\u00e7\u00e3o, trabalhar com algo que estivesse relacionado ao universo art\u00edstico parecia um sonho. Nessa \u00e9poca, tive meu primeiro contato com a arte contempor\u00e2nea, em uma exposi\u00e7\u00e3o da Lygia Clark no Ita\u00fa Cultural. <\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">O que me chamou a aten\u00e7\u00e3o foi que eles fizeram reprodu\u00e7\u00f5es das pe\u00e7as para que os visitantes pudessem experimentar diferentes sensa\u00e7\u00f5es. A mostra tinha desde os <\/span><i><span style=\"font-weight: 400;\">Bichos<\/span><\/i><span style=\"font-weight: 400;\">, que s\u00e3o aquelas placas de metal com dobradi\u00e7as, feitas para o p\u00fablico criar novas formas, at\u00e9 obras que envolviam um engajamento ainda maior do corpo do visitante. Lembro-me da obra <\/span><i><span style=\"font-weight: 400;\">T\u00fanel<\/span><\/i><span style=\"font-weight: 400;\">, que, como o nome sugere, consiste em um percurso feito de tecido el\u00e1stico, pelo qual a pessoa atravessa at\u00e9 alcan\u00e7ar a sa\u00edda. No in\u00edcio, a experi\u00eancia pode provocar uma sensa\u00e7\u00e3o de ang\u00fastia, de sufocamento; em seguida, surge o al\u00edvio. A obra pode ser interpretada como uma tentativa de fazer o visitante reviver, de forma sensorial, a experi\u00eancia do nascimento.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Experi\u00eancias como essa alimentaram o meu desejo de estudar Hist\u00f3ria da Arte,\u00a0 o que consegui realizar a partir do mestrado.<\/span> <span style=\"font-weight: 400;\">Lygia queria que a sua arte fosse vivenciada pelo corpo como um todo. Vis\u00e3o, audi\u00e7\u00e3o, tato, olfato e paladar apareciam em grupo, de forma multissensorial.\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Abordei esse tema no meu Trabalho de Conclus\u00e3o de Curso, na minha segunda gradua\u00e7\u00e3o, dessa vez no curso \u201cArte: Hist\u00f3ria Cr\u00edtica e Curadoria\u201d, da PUC. Desde a Gr\u00e9cia Antiga, a vis\u00e3o \u00e9 considerada o \u201cmais nobre dos sentidos\u201d, mas v\u00e1rios antrop\u00f3logos j\u00e1 mostraram que essa valoriza\u00e7\u00e3o \u00e9 cultural. Por isso queria saber como os museus podiam usar diversos recursos para ampliar as experi\u00eancias sensoriais dos visitantes, e estava justamente fazendo essa pesquisa quando fui ao Ipiranga pela primeira vez.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">N\u00e3o cheguei a conhecer o Museu antes de sua reabertura, em 2022. Ele foi fechado cerca de um ano ap\u00f3s a minha chegada a S\u00e3o Paulo, e n\u00e3o consegui visit\u00e1-lo a tempo. Mas, na minha primeira visita, fiquei totalmente fascinada em ver como a acessibilidade tinha import\u00e2ncia dentro das exposi\u00e7\u00f5es. Em outras institui\u00e7\u00f5es, os recursos de acessibilidade, quando existem, costumam ficar em espa\u00e7os pouco vis\u00edveis, separados das exposi\u00e7\u00f5es. No Museu do Ipiranga, ao contr\u00e1rio, eles ocupavam um lugar central no percurso expositivo. Al\u00e9m de recursos fundamentais, como textos em braille, audiodescri\u00e7\u00e3o e int\u00e9rpretes de Libras, chamou minha aten\u00e7\u00e3o a quantidade de obras e objetos acess\u00edveis ao toque, com formas e materiais diversos, ampliando as possibilidades de explora\u00e7\u00e3o dos conte\u00fados das exposi\u00e7\u00f5es.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nessa \u00e9poca, estava cursando o meu doutorado, que era sobre a transforma\u00e7\u00e3o de objetos populares em obras de arte. Mas ainda me sentia insegura sobre o que estava fazendo e passei a me questionar aonde aquilo ia me levar. O interesse pelo tema da acessibilidade surge ent\u00e3o como uma v\u00e1lvula de escape, como um assunto que eu queria pesquisar, mas sem o peso da minha tese.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Sempre tive um carinho especial pela educa\u00e7\u00e3o museal e, por muito tempo, busquei me manter nesse campo. J\u00e1 havia vivenciado experi\u00eancias muito significativas com educa\u00e7\u00e3o popular, e a decis\u00e3o de estudar arte se deve, em grande parte, \u00e0 minha atua\u00e7\u00e3o como educadora na 31\u00aa Bienal.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nessa experi\u00eancia profissional, entre a sele\u00e7\u00e3o, a forma\u00e7\u00e3o e o tempo da mostra, o processo durou quase um ano. Eu me juntei a um grupo interdisciplinar, com supervisores que vinham do teatro e faziam muitas proposi\u00e7\u00f5es de engajamento corporal. Foi um momento decisivo para que eu pudesse me soltar mais.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Era uma Bienal bastante experimental e ali o mundo se abriu. A gente sempre fala da rela\u00e7\u00e3o do p\u00fablico com a arte e o p\u00fablico aparece quase como um conceito abstrato. Mas, naquele contexto, percebi as particularidades de cada grupo com que tinha contato.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Entendi como era trabalhar com as crian\u00e7as e at\u00e9 com os adolescentes que chegavam com aquele ar indiferente. Em pouco tempo, me dei conta que os estudantes do ensino m\u00e9dio adoravam parar em frente ao v\u00eddeo do artista turco Halil Altindere, no qual um grupo de rap percorria a comunidade onde nasceu enquanto entoava letras sobre a sua realidade. Por outro lado, os mais novos se divertiam na instala\u00e7\u00e3o do Grupo Contrafil\u00e9, que prop\u00f4s uma s\u00e9rie de encontros em torno de um baob\u00e1 \u2013 como a \u00e1rvore vive em torno de 6 mil anos, a proposta do coletivo era t\u00ea-la como a guardi\u00e3 das nossas hist\u00f3rias.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Acho que o que eles vivenciaram ali foram momentos que ir\u00e3o levar para vida toda, assim como tamb\u00e9m tenho at\u00e9 hoje a mem\u00f3ria das vezes em que visitei a Bienal quando era mais nova. A arte tem esse poder de marcar a nossa vida e aflorar as nossas sensibilidades e \u00e9 exatamente esse impacto que busco trazer nas atividades do Educativo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Recentemente, o Museu recebeu um grande grupo de visitantes participantes do terceiro Encontro Nacional da Rede de Leitura Inclusiva, organizado pela Funda\u00e7\u00e3o Dorina Nowill. No grupo, havia pessoas com defici\u00eancia visual. Foi uma oportunidade maravilhosa para centrar a visita na explora\u00e7\u00e3o das obras t\u00e1teis presentes no Museu.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Iniciamos pela maquete do edif\u00edcio, localizada no Piso Jardim. Foi poss\u00edvel perceber seus detalhes por meio do toque. A partir dessa experi\u00eancia, conversamos sobre sua constru\u00e7\u00e3o, realizada entre 1885 e 1890, e sobre sua concep\u00e7\u00e3o como monumento em comemora\u00e7\u00e3o \u00e0 Proclama\u00e7\u00e3o da Independ\u00eancia, ocorrida em 1822.<\/span><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-8932 size-full\" src=\"https:\/\/museudoipiranga.org.br\/wp-content\/uploads\/2026\/07\/Nicole-arquivo-pessoal-1.png\" alt=\"\" width=\"800\" height=\"600\" srcset=\"https:\/\/museudoipiranga.org.br\/wp-content\/uploads\/2026\/07\/Nicole-arquivo-pessoal-1.png 800w, https:\/\/museudoipiranga.org.br\/wp-content\/uploads\/2026\/07\/Nicole-arquivo-pessoal-1-300x225.png 300w, https:\/\/museudoipiranga.org.br\/wp-content\/uploads\/2026\/07\/Nicole-arquivo-pessoal-1-150x113.png 150w, https:\/\/museudoipiranga.org.br\/wp-content\/uploads\/2026\/07\/Nicole-arquivo-pessoal-1-768x576.png 768w, https:\/\/museudoipiranga.org.br\/wp-content\/uploads\/2026\/07\/Nicole-arquivo-pessoal-1-16x12.png 16w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-8933 size-full\" src=\"https:\/\/museudoipiranga.org.br\/wp-content\/uploads\/2026\/07\/Nicole-arquivo-pessoal-2.png\" alt=\"\" width=\"800\" height=\"600\" srcset=\"https:\/\/museudoipiranga.org.br\/wp-content\/uploads\/2026\/07\/Nicole-arquivo-pessoal-2.png 800w, https:\/\/museudoipiranga.org.br\/wp-content\/uploads\/2026\/07\/Nicole-arquivo-pessoal-2-300x225.png 300w, https:\/\/museudoipiranga.org.br\/wp-content\/uploads\/2026\/07\/Nicole-arquivo-pessoal-2-150x113.png 150w, https:\/\/museudoipiranga.org.br\/wp-content\/uploads\/2026\/07\/Nicole-arquivo-pessoal-2-768x576.png 768w, https:\/\/museudoipiranga.org.br\/wp-content\/uploads\/2026\/07\/Nicole-arquivo-pessoal-2-16x12.png 16w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Tamb\u00e9m abordamos a inaugura\u00e7\u00e3o do Museu Paulista no local, em 1895, e a reforma realizada entre 2013 e 2022.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Expliquei que a maquete representa, em escala reduzida, um edif\u00edcio de grandes propor\u00e7\u00f5es, com 123 metros de largura, 31 metros de altura e 18 metros de profundidade. Nela, identificamos tanto a entrada original, pelas escadarias, quanto o acesso atual ao Museu, voltado para o espa\u00e7o de acolhimento onde est\u00e1vamos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A ideia era transmitir a magnitude do edif\u00edcio, elemento central na experi\u00eancia dos visitantes. Para ampliar a percep\u00e7\u00e3o espacial e sensorial, adotei uma estrat\u00e9gia sugerida pelo meu colega Vini, tamb\u00e9m educador no Museu: ao chegarmos ao sagu\u00e3o, o grupo foi convidado a abra\u00e7ar as robustas colunas do edif\u00edcio. A proposta contribuiu para intensificar a experi\u00eancia corporal e sensorial no espa\u00e7o.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O contato com as pesquisas cient\u00edficas que fundamentam as exposi\u00e7\u00f5es do Museu me descortinou um novo olhar para obras de arte que j\u00e1 eram velhas conhecidas por meio de materiais did\u00e1ticos. Essa mudan\u00e7a de perspectiva me marcou desde a primeira vez que estive na exposi\u00e7\u00e3o \u201cPassados Imaginados\u201d, ainda como visitante do Museu. Ao compreender as obras do acervo como documentos hist\u00f3ricos, passei a observar com mais aten\u00e7\u00e3o o contexto de sua produ\u00e7\u00e3o e as inten\u00e7\u00f5es dos diferentes agentes envolvidos. Al\u00e9m dos objetivos do artista, entram em cena, por exemplo, aqueles que encomendaram as obras, ampliando suas possibilidades de interpreta\u00e7\u00e3o. Esse novo olhar tamb\u00e9m se relaciona ao fato de que, at\u00e9 ent\u00e3o, eu analisava obras inseridas em contextos hist\u00f3ricos e art\u00edsticos distintos daqueles presentes no acervo do Museu, o que torna esse deslocamento ainda mais significativo.<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">Como as narrativas hist\u00f3ricas s\u00e3o constru\u00eddas?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Quem aparece como protagonista?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Que grupos foram historicamente apagados?<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">Pensar sobre essas quest\u00f5es \u00e9 uma das iniciativas atuais do Museu do Ipiranga. A ideia dos bandeirantes como figuras her\u00f3icas, por exemplo, foi uma imagem que a institui\u00e7\u00e3o ajudou a criar e divulgar, e que agora problematizamos com os visitantes, trazendo para discuss\u00e3o esse passado que tamb\u00e9m foi violento e escravizador.\u00a0 <\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">Quando visitei o Ipiranga depois da reabertura, jamais poderia imaginar que seria nesse pr\u00e9dio que realizaria o meu sonho de trabalhar com arte. Eu era aquela pessoa que frequentava apenas espa\u00e7os de arte contempor\u00e2nea, mesmo quando viajava, e a minha rela\u00e7\u00e3o com museus de hist\u00f3ria parecia distante.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Desde que comecei, em 2024, tenho buscado diariamente aprender mais e mais. O meu desejo \u00e9 articular esses novos conhecimentos com a bagagem que j\u00e1 trago comigo e que diz respeito \u00e0s pr\u00e1ticas art\u00edsticas do nosso tempo.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Na mostra \u201cDebret em Quest\u00e3o \u2013 Olhares Contempor\u00e2neos&#8221;, por exemplo, n\u00f3s, da equipe educativa, desenvolvemos, em di\u00e1logo com a curadoria, uma proposta de explora\u00e7\u00e3o sensorial que contemplou v\u00e1rias obras. Ao longo do percurso expositivo, mesas com recursos t\u00e1teis ampliam as possibilidades de frui\u00e7\u00e3o da exposi\u00e7\u00e3o.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por exemplo, na sala com fotografias da Escola de Samba Acad\u00eamicos do Salgueiro, que teve o Debret como tema do desfile em 1959, nossa ideia foi transformar o samba-enredo em vibra\u00e7\u00e3o. O desafio foi criar uma sincronia entre a letra e o som do samba-enredo, sua vers\u00e3o em Libras e a possibilidade de compreender essas informa\u00e7\u00f5es por meio do toque em uma superf\u00edcie.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se ca\u00ed no Museu do Ipiranga quase de paraquedas, sem saber exatamente onde estava aterrissando, hoje entendo que n\u00e3o foi por acaso. \u00c9 nesse espa\u00e7o, entre arte, hist\u00f3ria e educa\u00e7\u00e3o, que quero construir o meu lugar. Um sonho que estou realizando todos os dias.<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Ca\u00ed no Museu do Ipiranga de paraquedas.\u00a0 Quando prestei o concurso, em 2024, achei que era para trabalhar no Museu de Arqueologia e Etnologia da Universidade de S\u00e3o Paulo. J\u00e1 havia realizado uma disciplina no Museu, durante o mestrado, e visitado a exposi\u00e7\u00e3o Resist\u00eancia J\u00e1! Fortalecimento e uni\u00e3o das culturas ind\u00edgenas Kaingang, Guarani Nhandewa e [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":8662,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[25],"tags":[],"class_list":["post-8950","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entrevista"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Um sonho &#8211; Museu do Ipiranga<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/museudoipiranga.org.br\/en\/um-sonho\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Um sonho &#8211; Museu do Ipiranga\" \/>\n<meta property=\"og:description\" content=\"Ca\u00ed no Museu do Ipiranga de paraquedas.\u00a0 Quando prestei o concurso, em 2024, achei que era para trabalhar no Museu de Arqueologia e Etnologia da Universidade de S\u00e3o Paulo. J\u00e1 havia realizado uma disciplina no Museu, durante o mestrado, e visitado a exposi\u00e7\u00e3o Resist\u00eancia J\u00e1! Fortalecimento e uni\u00e3o das culturas ind\u00edgenas Kaingang, Guarani Nhandewa e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/museudoipiranga.org.br\/en\/um-sonho\/\" \/>\n<meta property=\"og:site_name\" content=\"Museu do Ipiranga\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/museudoipiranga\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-14T21:04:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/museudoipiranga.org.br\/wp-content\/uploads\/2026\/07\/Card_historias-compartilhadas_Nicole.png\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"614\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Lucas provoque\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@museupaulista\" \/>\n<meta name=\"twitter:site\" content=\"@museupaulista\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lucas provoque\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/museudoipiranga.org.br\\\/um-sonho\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/museudoipiranga.org.br\\\/um-sonho\\\/\"},\"author\":{\"name\":\"Lucas provoque\",\"@id\":\"https:\\\/\\\/museudoipiranga.org.br\\\/#\\\/schema\\\/person\\\/84ab73451c0f367f6a715caacb2688f2\"},\"headline\":\"Um sonho\",\"datePublished\":\"2026-07-14T21:04:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/museudoipiranga.org.br\\\/um-sonho\\\/\"},\"wordCount\":1882,\"publisher\":{\"@id\":\"https:\\\/\\\/museudoipiranga.org.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/museudoipiranga.org.br\\\/um-sonho\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/museudoipiranga.org.br\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Card_historias-compartilhadas_Nicole.png\",\"articleSection\":[\"Hist\u00f3rias Compartilhadas\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/museudoipiranga.org.br\\\/um-sonho\\\/\",\"url\":\"https:\\\/\\\/museudoipiranga.org.br\\\/um-sonho\\\/\",\"name\":\"Um sonho &#8211; Museu do Ipiranga\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/museudoipiranga.org.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/museudoipiranga.org.br\\\/um-sonho\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/museudoipiranga.org.br\\\/um-sonho\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/museudoipiranga.org.br\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Card_historias-compartilhadas_Nicole.png\",\"datePublished\":\"2026-07-14T21:04:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/museudoipiranga.org.br\\\/um-sonho\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/museudoipiranga.org.br\\\/um-sonho\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/museudoipiranga.org.br\\\/um-sonho\\\/#primaryimage\",\"url\":\"https:\\\/\\\/museudoipiranga.org.br\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Card_historias-compartilhadas_Nicole.png\",\"contentUrl\":\"https:\\\/\\\/museudoipiranga.org.br\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Card_historias-compartilhadas_Nicole.png\",\"width\":900,\"height\":614},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/museudoipiranga.org.br\\\/um-sonho\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/museudoipiranga.org.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Um sonho\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/museudoipiranga.org.br\\\/#website\",\"url\":\"https:\\\/\\\/museudoipiranga.org.br\\\/\",\"name\":\"Museu do Ipiranga\",\"description\":\"O Museu do Ipiranga \u00e9 a sede do Museu Paulista, que \u00e9 um museu especializado em hist\u00f3ria e cultural material e integra a Universidade de S\u00e3o Paulo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/museudoipiranga.org.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/museudoipiranga.org.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/museudoipiranga.org.br\\\/#organization\",\"name\":\"Museu do Ipiranga\",\"url\":\"https:\\\/\\\/museudoipiranga.org.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/museudoipiranga.org.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/museudoipiranga.org.br\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/logo-museu.svg\",\"contentUrl\":\"https:\\\/\\\/museudoipiranga.org.br\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/logo-museu.svg\",\"width\":173,\"height\":140,\"caption\":\"Museu do Ipiranga\"},\"image\":{\"@id\":\"https:\\\/\\\/museudoipiranga.org.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/museudoipiranga\\\/\",\"https:\\\/\\\/x.com\\\/museupaulista\",\"https:\\\/\\\/www.instagram.com\\\/museudoipiranga\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/museu-do-ipiranga\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC98l9dLKN5cyDPo4hE-A_tA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/museudoipiranga.org.br\\\/#\\\/schema\\\/person\\\/84ab73451c0f367f6a715caacb2688f2\",\"name\":\"Lucas provoque\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0920f2837b80f5ec755ded93d131899b6c00a4cea0d2119aa5ea1a93cfd90e1b?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0920f2837b80f5ec755ded93d131899b6c00a4cea0d2119aa5ea1a93cfd90e1b?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0920f2837b80f5ec755ded93d131899b6c00a4cea0d2119aa5ea1a93cfd90e1b?s=96&d=blank&r=g\",\"caption\":\"Lucas provoque\"},\"url\":\"https:\\\/\\\/museudoipiranga.org.br\\\/en\\\/author\\\/lucasprovoquepublicidade-com-br\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Um sonho &#8211; Museu do Ipiranga","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/museudoipiranga.org.br\/en\/um-sonho\/","og_locale":"en_US","og_type":"article","og_title":"Um sonho &#8211; Museu do Ipiranga","og_description":"Ca\u00ed no Museu do Ipiranga de paraquedas.\u00a0 Quando prestei o concurso, em 2024, achei que era para trabalhar no Museu de Arqueologia e Etnologia da Universidade de S\u00e3o Paulo. J\u00e1 havia realizado uma disciplina no Museu, durante o mestrado, e visitado a exposi\u00e7\u00e3o Resist\u00eancia J\u00e1! Fortalecimento e uni\u00e3o das culturas ind\u00edgenas Kaingang, Guarani Nhandewa e [&hellip;]","og_url":"https:\/\/museudoipiranga.org.br\/en\/um-sonho\/","og_site_name":"Museu do Ipiranga","article_publisher":"https:\/\/www.facebook.com\/museudoipiranga\/","article_published_time":"2026-07-14T21:04:10+00:00","og_image":[{"width":900,"height":614,"url":"https:\/\/museudoipiranga.org.br\/wp-content\/uploads\/2026\/07\/Card_historias-compartilhadas_Nicole.png","type":"image\/png"}],"author":"Lucas provoque","twitter_card":"summary_large_image","twitter_creator":"@museupaulista","twitter_site":"@museupaulista","twitter_misc":{"Written by":"Lucas provoque","Est. reading time":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/museudoipiranga.org.br\/um-sonho\/#article","isPartOf":{"@id":"https:\/\/museudoipiranga.org.br\/um-sonho\/"},"author":{"name":"Lucas provoque","@id":"https:\/\/museudoipiranga.org.br\/#\/schema\/person\/84ab73451c0f367f6a715caacb2688f2"},"headline":"Um sonho","datePublished":"2026-07-14T21:04:10+00:00","mainEntityOfPage":{"@id":"https:\/\/museudoipiranga.org.br\/um-sonho\/"},"wordCount":1882,"publisher":{"@id":"https:\/\/museudoipiranga.org.br\/#organization"},"image":{"@id":"https:\/\/museudoipiranga.org.br\/um-sonho\/#primaryimage"},"thumbnailUrl":"https:\/\/museudoipiranga.org.br\/wp-content\/uploads\/2026\/07\/Card_historias-compartilhadas_Nicole.png","articleSection":["Hist\u00f3rias Compartilhadas"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/museudoipiranga.org.br\/um-sonho\/","url":"https:\/\/museudoipiranga.org.br\/um-sonho\/","name":"Um sonho &#8211; Museu do Ipiranga","isPartOf":{"@id":"https:\/\/museudoipiranga.org.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/museudoipiranga.org.br\/um-sonho\/#primaryimage"},"image":{"@id":"https:\/\/museudoipiranga.org.br\/um-sonho\/#primaryimage"},"thumbnailUrl":"https:\/\/museudoipiranga.org.br\/wp-content\/uploads\/2026\/07\/Card_historias-compartilhadas_Nicole.png","datePublished":"2026-07-14T21:04:10+00:00","breadcrumb":{"@id":"https:\/\/museudoipiranga.org.br\/um-sonho\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/museudoipiranga.org.br\/um-sonho\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/museudoipiranga.org.br\/um-sonho\/#primaryimage","url":"https:\/\/museudoipiranga.org.br\/wp-content\/uploads\/2026\/07\/Card_historias-compartilhadas_Nicole.png","contentUrl":"https:\/\/museudoipiranga.org.br\/wp-content\/uploads\/2026\/07\/Card_historias-compartilhadas_Nicole.png","width":900,"height":614},{"@type":"BreadcrumbList","@id":"https:\/\/museudoipiranga.org.br\/um-sonho\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/museudoipiranga.org.br\/"},{"@type":"ListItem","position":2,"name":"Um sonho"}]},{"@type":"WebSite","@id":"https:\/\/museudoipiranga.org.br\/#website","url":"https:\/\/museudoipiranga.org.br\/","name":"Ipiranga Museum","description":"The Ipiranga Museum is the headquarters of the Paulista Museum, which is a museum specializing in historical and material culture and is part of the University of S\u00e3o Paulo.","publisher":{"@id":"https:\/\/museudoipiranga.org.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/museudoipiranga.org.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/museudoipiranga.org.br\/#organization","name":"Ipiranga Museum","url":"https:\/\/museudoipiranga.org.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/museudoipiranga.org.br\/#\/schema\/logo\/image\/","url":"https:\/\/museudoipiranga.org.br\/wp-content\/uploads\/2024\/09\/logo-museu.svg","contentUrl":"https:\/\/museudoipiranga.org.br\/wp-content\/uploads\/2024\/09\/logo-museu.svg","width":173,"height":140,"caption":"Museu do Ipiranga"},"image":{"@id":"https:\/\/museudoipiranga.org.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/museudoipiranga\/","https:\/\/x.com\/museupaulista","https:\/\/www.instagram.com\/museudoipiranga\/","https:\/\/www.linkedin.com\/company\/museu-do-ipiranga\/","https:\/\/www.youtube.com\/channel\/UC98l9dLKN5cyDPo4hE-A_tA"]},{"@type":"Person","@id":"https:\/\/museudoipiranga.org.br\/#\/schema\/person\/84ab73451c0f367f6a715caacb2688f2","name":"Lucas provoke","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/0920f2837b80f5ec755ded93d131899b6c00a4cea0d2119aa5ea1a93cfd90e1b?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0920f2837b80f5ec755ded93d131899b6c00a4cea0d2119aa5ea1a93cfd90e1b?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0920f2837b80f5ec755ded93d131899b6c00a4cea0d2119aa5ea1a93cfd90e1b?s=96&d=blank&r=g","caption":"Lucas provoque"},"url":"https:\/\/museudoipiranga.org.br\/en\/author\/lucasprovoquepublicidade-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/museudoipiranga.org.br\/en\/wp-json\/wp\/v2\/posts\/8950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/museudoipiranga.org.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/museudoipiranga.org.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/museudoipiranga.org.br\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/museudoipiranga.org.br\/en\/wp-json\/wp\/v2\/comments?post=8950"}],"version-history":[{"count":1,"href":"https:\/\/museudoipiranga.org.br\/en\/wp-json\/wp\/v2\/posts\/8950\/revisions"}],"predecessor-version":[{"id":8951,"href":"https:\/\/museudoipiranga.org.br\/en\/wp-json\/wp\/v2\/posts\/8950\/revisions\/8951"}],"wp:attachment":[{"href":"https:\/\/museudoipiranga.org.br\/en\/wp-json\/wp\/v2\/media?parent=8950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/museudoipiranga.org.br\/en\/wp-json\/wp\/v2\/categories?post=8950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/museudoipiranga.org.br\/en\/wp-json\/wp\/v2\/tags?post=8950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}